{"id":5257,"date":"2023-02-20T16:20:31","date_gmt":"2023-02-20T16:20:31","guid":{"rendered":"https:\/\/www.pocom.io\/?page_id=5257"},"modified":"2023-02-20T16:39:09","modified_gmt":"2023-02-20T16:39:09","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/www.pocom.io\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5257\" class=\"elementor elementor-5257\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6e9535 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6e9535\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-310b448\" data-id=\"310b448\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4041d80 elementor-widget elementor-widget-text-editor\" data-id=\"4041d80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\"><strong>POLITIQUE DE CONFIDENTIALIT\u00c9<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong>DONN\u00c9ES PERSONNELLES<\/strong><\/h1>\n<h2>D\u00e9finitions<\/h2>\n<p>L&rsquo;\u00c9diteur : La personne, physique ou morale, qui \u00e9dite les services de communication au public en ligne.<\/p>\n<p>Le Site : L&rsquo;ensemble des sites, pages Internet et services en ligne propos\u00e9s par l&rsquo;\u00c9diteur.<\/p>\n<p>L&rsquo;Utilisateur : La personne utilisant le Site et les services.<\/p>\n<p><\/p>\n<h3>1- Nature des donn\u00e9es collect\u00e9es<\/h3>\n<p>Dans le cadre de l&rsquo;utilisation des Sites, l&rsquo;\u00c9diteur est susceptible de collecter les cat\u00e9gories de donn\u00e9es suivantes concernant ses Utilisateurs :&nbsp;Donn\u00e9es de connexion (adresses IP, journaux d&rsquo;\u00e9v\u00e9nements&#8230;)<\/p>\n<p><\/p>\n<h3>2- Communication des donn\u00e9es personnelles \u00e0 des tiers<\/h3>\n<p><\/p>\n<p>Pas de communication \u00e0 des tiers<\/p>\n<p>Vos donn\u00e9es ne font l&rsquo;objet d&rsquo;aucune communication \u00e0 des tiers. Vous \u00eates toutefois inform\u00e9s qu&rsquo;elles pourront \u00eatre divulgu\u00e9es en application d&rsquo;une loi, d&rsquo;un r\u00e8glement ou en vertu d&rsquo;une d\u00e9cision d&rsquo;une autorit\u00e9 r\u00e9glementaire ou judiciaire comp\u00e9tente.<\/p>\n<p><\/p>\n<h3>3- Information pr\u00e9alable pour la communication des donn\u00e9es personnelles \u00e0 des tiers en cas de fusion \/ absorption<\/h3>\n<p>Information pr\u00e9alable et possibilit\u00e9 d\u2019opt-out avant et apr\u00e8s la fusion \/ acquisition<\/p>\n<p>Dans le cas o\u00f9 nous prendrions part \u00e0 une op\u00e9ration de fusion, d\u2019acquisition ou \u00e0 toute autre forme de cession d\u2019actifs, nous nous engageons \u00e0 garantir la confidentialit\u00e9 de vos donn\u00e9es personnelles et \u00e0 vous informer avant que celles-ci ne soient transf\u00e9r\u00e9es ou soumises \u00e0 de nouvelles r\u00e8gles de confidentialit\u00e9.<\/p>\n<p><\/p>\n<h3>4- Agr\u00e9gation des donn\u00e9es<\/h3>\n<p>Agr\u00e9gation avec des donn\u00e9es non personnelles<\/p>\n<p>Nous pouvons publier, divulguer et utiliser les informations agr\u00e9g\u00e9es (informations relatives \u00e0 tous nos Utilisateurs ou \u00e0 des groupes ou cat\u00e9gories sp\u00e9cifiques d&rsquo;Utilisateurs que nous combinons de mani\u00e8re \u00e0 ce qu&rsquo;un Utilisateur individuel ne puisse plus \u00eatre identifi\u00e9 ou mentionn\u00e9) et les informations non personnelles \u00e0 des fins d&rsquo;analyse du secteur et du march\u00e9, de profilage d\u00e9mographique, \u00e0 des fins promotionnelles et publicitaires et \u00e0 d&rsquo;autres fins commerciales.<\/p>\n<p>Agr\u00e9gation avec des donn\u00e9es personnelles disponibles sur les comptes sociaux de l&rsquo;Utilisateur<\/p>\n<p>Si vous connectez votre compte \u00e0 un compte d\u2019un autre service afin de faire des envois crois\u00e9s, ledit service pourra nous communiquer vos informations de profil, de connexion, ainsi que toute autre information dont vous avez autoris\u00e9 la divulgation. Nous pouvons agr\u00e9ger les informations relatives \u00e0 tous nos autres Utilisateurs, groupes, comptes, aux donn\u00e9es personnelles disponibles sur l\u2019Utilisateur.<\/p>\n<p><\/p>\n<h3>5- Collecte des donn\u00e9es d&rsquo;identit\u00e9<\/h3>\n<p>Consultation libre<\/p>\n<p>La consultation du Site ne n\u00e9cessite pas d&rsquo;inscription ni d&rsquo;identification pr\u00e9alable. Elle peut s&rsquo;effectuer sans que vous ne communiquiez de donn\u00e9es nominatives vous concernant (nom, pr\u00e9nom, adresse, etc). Nous ne proc\u00e9dons \u00e0 aucun enregistrement de donn\u00e9es nominatives pour la simple consultation du Site.<\/p>\n<p>6- Collecte des donn\u00e9es d&rsquo;identification<\/p>\n<p>Utilisation de l&rsquo;identifiant de l\u2019utilisateur uniquement pour l\u2019acc\u00e8s aux services<\/p>\n<p>Nous utilisons vos identifiants \u00e9lectroniques seulement pour et pendant l&rsquo;ex\u00e9cution du contrat.<\/p>\n<p><\/p>\n<h3>7- Collecte des donn\u00e9es du terminal<\/h3>\n<p>Collecte des donn\u00e9es de profilage et des donn\u00e9es techniques \u00e0 des fins de fourniture&nbsp;<span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">du service<\/span><\/p>\n<p>Certaines des donn\u00e9es techniques de votre appareil sont collect\u00e9es automatiquement par le Site. Ces informations incluent notamment votre adresse IP, fournisseur d&rsquo;acc\u00e8s \u00e0 Internet, configuration mat\u00e9rielle, configuration logicielle, type et langue du navigateur&#8230; La collecte de ces donn\u00e9es est n\u00e9cessaire \u00e0 la fourniture des services.<\/p>\n<p>Collecte des donn\u00e9es techniques \u00e0 des fins publicitaires, commerciales et statistiques<\/p>\n<p>Les donn\u00e9es techniques de votre appareil sont automatiquement collect\u00e9es et enregistr\u00e9es par le Site, \u00e0 des fins publicitaires, commerciales et statistiques. Ces informations nous aident \u00e0 personnaliser et \u00e0 am\u00e9liorer continuellement votre exp\u00e9rience sur notre Site. Nous ne collectons ni ne conservons aucune donn\u00e9e nominative (nom, pr\u00e9nom, adresse&#8230;) \u00e9ventuellement attach\u00e9e \u00e0 une donn\u00e9e technique. Les donn\u00e9es collect\u00e9es sont susceptibles d\u2019\u00eatre revendues \u00e0 des tiers.<\/p>\n<p><\/p>\n<h3>8- Cookies<\/h3>\n<p>Dur\u00e9e de conservation des cookies<\/p>\n<p>Conform\u00e9ment aux recommandations de la CNIL, la dur\u00e9e maximale de conservation des cookies est de 13 mois au maximum apr\u00e8s leur premier d\u00e9p\u00f4t dans le terminal de l&rsquo;Utilisateur, tout comme la dur\u00e9e de la validit\u00e9 du consentement de l\u2019Utilisateur \u00e0 l\u2019utilisation de ces cookies. La dur\u00e9e de vie des cookies n\u2019est pas prolong\u00e9e \u00e0 chaque visite. Le consentement de l\u2019Utilisateur devra donc \u00eatre renouvel\u00e9 \u00e0 l&rsquo;issue de ce d\u00e9lai.<\/p>\n<p><\/p>\n<p>Finalit\u00e9 cookies<\/p>\n<p>Les cookies peuvent \u00eatre utilis\u00e9s pour des fins statistiques notamment pour optimiser les services rendus \u00e0 l&rsquo;Utilisateur, \u00e0 partir du traitement des informations concernant la fr\u00e9quence d&rsquo;acc\u00e8s, la personnalisation des pages ainsi que les op\u00e9rations r\u00e9alis\u00e9es et les informations consult\u00e9es.<\/p>\n<p>Vous \u00eates inform\u00e9 que l&rsquo;\u00c9diteur est susceptible de d\u00e9poser des cookies sur votre terminal. Le cookie enregistre des informations relatives \u00e0 la navigation sur le service (les pages que vous avez consult\u00e9es, la date et l&rsquo;heure de la consultation&#8230;) que nous pourrons lire lors de vos visites ult\u00e9rieures.<\/p>\n<p>Droit de l&rsquo;Utilisateur de refuser les cookies, la d\u00e9sactivation entra\u00eenant un fonctionnement d\u00e9grad\u00e9 du service. Vous reconnaissez avoir \u00e9t\u00e9 inform\u00e9 que l&rsquo;\u00c9diteur peut avoir recours \u00e0 des cookies, et l&rsquo;y autorisez. Si vous ne souhaitez pas que des cookies soient utilis\u00e9s sur votre terminal, la plupart des navigateurs vous permettent de d\u00e9sactiver les cookies en passant par les options de r\u00e9glage. Toutefois, vous \u00eates inform\u00e9 que certains services sont susceptibles de ne plus fonctionner correctement.<\/p>\n<p>Association possible des cookies avec des donn\u00e9es personnelles pour permettre le fonctionnement du service<\/p>\n<p>L&rsquo;\u00c9diteur peut \u00eatre amen\u00e9e \u00e0 recueillir des informations de navigation via l&rsquo;utilisation de cookies.<\/p>\n<p><\/p>\n<h3>9 &#8211; Conservation des donn\u00e9es techniques<\/h3>\n<p>Dur\u00e9e de conservation des donn\u00e9es techniques<\/p>\n<p>Les donn\u00e9es techniques sont conserv\u00e9es pour la dur\u00e9e strictement n\u00e9cessaire \u00e0 la r\u00e9alisation des finalit\u00e9s vis\u00e9es ci-avant.<\/p>\n<p><\/p>\n<h3>10- D\u00e9lai de conservation des donn\u00e9es personnelles et d&rsquo;anonymisation<\/h3>\n<p>Conservation des donn\u00e9es pendant la dur\u00e9e de la relation contractuelle<\/p>\n<p>Conform\u00e9ment \u00e0 l&rsquo;article 6-5\u00b0 de la loi n\u00b078-17 du 6 janvier 1978 relative \u00e0 l&rsquo;informatique, aux fichiers et aux libert\u00e9s, les donn\u00e9es \u00e0 caract\u00e8re personnel faisant l&rsquo;objet d&rsquo;un traitement ne sont pas conserv\u00e9es au-del\u00e0 du temps n\u00e9cessaire \u00e0 l&rsquo;ex\u00e9cution des obligations d\u00e9finies lors de la conclusion du contrat ou de la dur\u00e9e pr\u00e9d\u00e9finie de la relation contractuelle.<\/p>\n<p>Conservation des donn\u00e9es anonymis\u00e9es au del\u00e0 de la relation contractuelle \/ apr\u00e8s la suppression du compte<\/p>\n<p>Nous conservons les donn\u00e9es personnelles pour la dur\u00e9e strictement n\u00e9cessaire \u00e0 la r\u00e9alisation des finalit\u00e9s d\u00e9crites dans les pr\u00e9sentes Politiques de confidentialit\u00e9. Au-del\u00e0 de cette dur\u00e9e, elles seront anonymis\u00e9es et conserv\u00e9es \u00e0 des fins exclusivement statistiques et ne donneront lieu \u00e0 aucune exploitation, de quelque nature que ce soit.<\/p>\n<p>Suppression des donn\u00e9es apr\u00e8s suppression du compte<\/p>\n<p>Des moyens de purge de donn\u00e9es sont mis en place afin d&rsquo;en pr\u00e9voir la suppression effective d\u00e8s lors que la dur\u00e9e de conservation ou d&rsquo;archivage n\u00e9cessaire \u00e0 l&rsquo;accomplissement des finalit\u00e9s d\u00e9termin\u00e9es ou impos\u00e9es est atteinte. Conform\u00e9ment \u00e0 la loi n\u00b078-17 du 6 janvier 1978 relative \u00e0 l&rsquo;informatique, aux fichiers et aux libert\u00e9s, vous disposez par ailleurs d&rsquo;un droit de suppression sur vos donn\u00e9es que vous pouvez exercer \u00e0 tout moment en prenant contact avec l&rsquo;\u00c9diteur.<\/p>\n<p>Suppression des donn\u00e9es apr\u00e8s 3 ans d&rsquo;inactivit\u00e9<\/p>\n<p>Pour des raisons de s\u00e9curit\u00e9, si vous ne vous \u00eates pas authentifi\u00e9 sur le Site pendant une p\u00e9riode de trois ans, vous recevrez un e-mail vous invitant \u00e0 vous connecter dans les plus brefs d\u00e9lais, sans quoi vos donn\u00e9es seront supprim\u00e9es de nos bases de donn\u00e9es.&nbsp;<\/p>\n<p><\/p>\n<h3>11- Suppression du compte<p><\/p>\n<\/h3>\n<p>Suppression du compte \u00e0 la demande<\/p>\n<p>L&rsquo;Utilisateur a la possibilit\u00e9 de supprimer son Compte \u00e0 tout moment, par simple demande \u00e0 l&rsquo;\u00c9diteur OU par le menu de suppression de Compte pr\u00e9sent dans les param\u00e8tres du Compte le cas \u00e9ch\u00e9ant.<\/p>\n<p>Suppression du compte en cas de violation de la Politique de Confidentialit\u00e9<\/p>\n<p>En cas de violation d&rsquo;une ou de plusieurs dispositions de la Politique de Confidentialit\u00e9 ou de tout autre document incorpor\u00e9 aux pr\u00e9sentes par r\u00e9f\u00e9rence, l&rsquo;\u00c9diteur se r\u00e9serve le droit de mettre fin ou restreindre sans aucun avertissement pr\u00e9alable et \u00e0 sa seule discr\u00e9tion, votre usage et acc\u00e8s aux services, \u00e0 votre compte et \u00e0&nbsp;<span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">tous les Sites.<\/span><\/p>\n<p><\/p>\n<h3>12- Indications en cas de faille de s\u00e9curit\u00e9 d\u00e9cel\u00e9e par l&rsquo;\u00c9diteur<p><\/p>\n<\/h3>\n<p>Information de l&rsquo;Utilisateur en cas de faille de s\u00e9curit\u00e9<\/p>\n<p>Nous nous engageons \u00e0 mettre en oeuvre toutes les mesures techniques et organisationnelles appropri\u00e9es afin de garantir un niveau de s\u00e9curit\u00e9 adapt\u00e9 au regard des risques d&rsquo;acc\u00e8s accidentels, non autoris\u00e9s ou ill\u00e9gaux, de divulgation, d&rsquo;alt\u00e9ration, de perte ou encore de destruction des donn\u00e9es personnelles vous concernant. Dans l&rsquo;\u00e9ventualit\u00e9 o\u00f9 nous prendrions connaissance d&rsquo;un acc\u00e8s ill\u00e9gal aux donn\u00e9es personnelles vous concernant stock\u00e9es sur nos serveurs ou ceux de nos prestataires, ou d&rsquo;un acc\u00e8s non autoris\u00e9 ayant pour cons\u00e9quence la r\u00e9alisation des risques identifi\u00e9s ci-dessus, nous nous engageons \u00e0 :<\/p>\n<p>Vous notifier l&rsquo;incident dans les plus brefs d\u00e9lais ;<\/p>\n<p>Examiner les causes de l&rsquo;incident et vous en informer ;<br><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">Prendre les mesures n\u00e9cessaires dans la limite du raisonnable afin d&rsquo;amoindrir les effets n\u00e9gatifs&nbsp;<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">et pr\u00e9judices pouvant r\u00e9sulter dudit incident.<\/span><\/p>\n<p>Limitation de la responsabilit\u00e9<\/p>\n<p>En aucun cas les engagements d\u00e9finis au point ci-dessus relatifs \u00e0 la notification en cas de faille de s\u00e9curit\u00e9 ne peuvent \u00eatre assimil\u00e9s \u00e0 une quelconque reconnaissance de faute ou de responsabilit\u00e9 quant \u00e0 la survenance de l&rsquo;incident en question.<\/p>\n<p><\/p>\n<h3>13- Transfert des donn\u00e9es personnelles \u00e0 l&rsquo;\u00e9tranger<p><\/p>\n<\/h3>\n<p>Pas de transfert en dehors de l&rsquo;Union europ\u00e9enne<\/p>\n<p>L&rsquo;\u00c9diteur s&rsquo;engage \u00e0 ne pas transf\u00e9rer les donn\u00e9es personnelles de ses Utilisateurs en dehors<br>de l&rsquo;Union europ\u00e9enne.<br>https:\/\/www.cnil.fr\/fr\/la-protection-des-donnees-dans-le-mondehttps:\/\/www.cnil.fr\/fr\/la-protectiondes-donnees-dans-le-monde<\/p>\n<p><\/p>\n<h3>14- Modification de la politique de confidentialit\u00e9<p><\/p>\n<\/h3>\n<p>En cas de modification de la pr\u00e9sente Politique de Confidentialit\u00e9, engagement de ne pas baisser le niveau de confidentialit\u00e9 de mani\u00e8re substantielle sans l&rsquo;information pr\u00e9alable des personnes concern\u00e9es<\/p>\n<p>Nous nous engageons \u00e0 vous informer en cas de modification substantielle de la pr\u00e9sente Politique de Confidentialit\u00e9, et \u00e0 ne pas baisser le niveau de confidentialit\u00e9 de vos donn\u00e9es de mani\u00e8re substantielle sans vous en informer et obtenir votre consentement.<\/p>\n<p><\/p>\n<h3>15- Droit applicable et modalit\u00e9s de recours<p><\/p>\n<\/h3>\n<p>Application du droit fran\u00e7ais (l\u00e9gislation CNIL) et comp\u00e9tence des tribunaux&nbsp;<\/p>\n<p>La pr\u00e9sente Politique de Confidentialit\u00e9 et votre utilisation du Site sont r\u00e9gies et interpr\u00e9t\u00e9es conform\u00e9ment aux lois de France, et notamment \u00e0 la Loi n\u00b0 78-17 du 6 janvier 1978 relative \u00e0 l&rsquo;informatique, aux fichiers et aux libert\u00e9s. Le choix de la loi applicable ne porte pas atteinte \u00e0 vos droits en tant que consommateur conform\u00e9ment \u00e0 la loi applicable de votre lieu de r\u00e9sidence. Si vous \u00eates un consommateur, vous et nous acceptons de se soumettre \u00e0 la comp\u00e9tence nonexclusive des juridictions fran\u00e7aises, ce qui signifie que vous pouvez engager une action relative \u00e0 la pr\u00e9sente Politique de Confidentialit\u00e9 en France ou dans le pays de l&rsquo;UE dans lequel vous vivez. Si vous \u00eates un professionnel, toutes les actions \u00e0 notre encontre doivent \u00eatre engag\u00e9es devant une juridiction en France.<\/p>\n<p>En cas de litige, les parties chercheront une solution amiable avant toute action judiciaire. En cas d&rsquo;\u00e9chec de ces tentatives, toutes contestations \u00e0 la validit\u00e9, l&rsquo;interpr\u00e9tation et \/ ou l&rsquo;ex\u00e9cution de la Politique de Confidentialit\u00e9 devront \u00eatre port\u00e9es m\u00eame en cas de pluralit\u00e9 des d\u00e9fendeurs ou d&rsquo;appel en garantie, devant&nbsp;<span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">les tribunaux fran\u00e7ais.<\/span><\/p>\n<p><\/p>\n<h3>16- Portabilit\u00e9 des donn\u00e9es<p><\/p>\n<\/h3>\n<p>Portabilit\u00e9 des donn\u00e9es<\/p>\n<p>L&rsquo;\u00c9diteur s&rsquo;engage \u00e0 vous offrir la possibilit\u00e9 de vous faire restituer l&rsquo;ensemble des donn\u00e9es vous concernant sur simple demande. L&rsquo;Utilisateur se voit ainsi garantir une meilleure ma\u00eetrise de ses donn\u00e9es, et garde la possibilit\u00e9 de les r\u00e9utiliser. Ces donn\u00e9es devront \u00eatre fournies dans un format ouvert et ais\u00e9ment r\u00e9utilisable<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>POLITIQUE DE CONFIDENTIALIT\u00c9 DONN\u00c9ES PERSONNELLES D\u00e9finitions L&rsquo;\u00c9diteur : La personne, physique ou morale, qui \u00e9dite les services de communication au public en ligne. Le Site : L&rsquo;ensemble des sites, pages Internet et services en ligne propos\u00e9s par l&rsquo;\u00c9diteur. L&rsquo;Utilisateur : La personne utilisant le Site et les services. 1- Nature des donn\u00e9es collect\u00e9es Dans le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-5257","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.pocom.io\/fr\/wp-json\/wp\/v2\/pages\/5257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pocom.io\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pocom.io\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pocom.io\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pocom.io\/fr\/wp-json\/wp\/v2\/comments?post=5257"}],"version-history":[{"count":0,"href":"https:\/\/www.pocom.io\/fr\/wp-json\/wp\/v2\/pages\/5257\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pocom.io\/fr\/wp-json\/wp\/v2\/media?parent=5257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}